{"id":3812,"date":"2022-03-17T15:57:58","date_gmt":"2022-03-17T15:57:58","guid":{"rendered":"https:\/\/www.vintagefiets.be\/?p=3812"},"modified":"2022-03-17T16:00:38","modified_gmt":"2022-03-17T16:00:38","slug":"fiets-in-de-kijker-rossin-replica-jaren-80","status":"publish","type":"post","link":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/","title":{"rendered":"Bicycle in the spot: Rossin replica from the 80's"},"content":{"rendered":"<p>The bike in the spotlight this time is a Replica of an Italian Rossin from the early 1980s.<\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin03-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3818\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin03-1024x496.jpg\" alt=\"Rossin racefiets\" width=\"1024\" height=\"496\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin03-1024x496.jpg 1024w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin03-980x474.jpg 980w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin03-480x232.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin_CX.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3839\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin_CX.jpg\" alt=\"Rossin racefiets\" width=\"919\" height=\"664\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin_CX.jpg 919w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin_CX-480x347.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 919px, 100vw\" \/><\/a><\/p>\n<p>Why a replica? Firstly because I do not yet own a real Rossin and secondly because it is a very nice replica to which no changes have been made. The bike is still in its original condition from the early 1980s.<\/p>\n<p>Rossin's history is fairly short and the brand was only founded in 1974 by Marco Rossin, one of Colnago's best frame builders. More about Rossin's history will follow in a subsequent article.<\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin23-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3819 aligncenter\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin23-496x1024.jpg\" alt=\"Rossin racefiets\" width=\"496\" height=\"1024\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin23-496x1024.jpg 496w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin23-480x992.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 496px, 100vw\" \/><\/a><\/p>\n<p>This replica has the decals of the 2nd generation as can also be seen on the racing bikes of the teams from the 80s such as Jacky Aernoudt \u2013 Rossin, Hitachi \u2013 Marc Zeepcentrale. Many famous cyclists once rode a Rossin racing bike, just think of Claude Criquielion, Eric Vanderaerden, Hennie Kuiper, Roger De Vlaeminck, etc.<\/p>\n<div id=\"attachment_3820\" style=\"width: 304px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin-Vanderaerden-1983.png\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-3820\" class=\"size-full wp-image-3820\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin-Vanderaerden-1983.png\" alt=\"Rossin Vanderaerden\" width=\"294\" height=\"493\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin-Vanderaerden-1983.png 294w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin-Vanderaerden-1983-179x300.png 179w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin-Vanderaerden-1983-7x12.png 7w\" sizes=\"auto, (max-width: 294px) 100vw, 294px\" \/><\/a><p id=\"caption-attachment-3820\" class=\"wp-caption-text\">Eric Vanderaerden on his Rossin racing bicycle in 1983<\/p><\/div>\n<p>The bicycle is still completely in its original condition and equipped with a New Shimano 600 Ex group as can be found in the catalog from 1983. It is unknown which tubes the frame is made from, but it does have Shimano pads.<\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-01.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3814\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-01-1024x569.png\" alt=\"New Shimano 600 Ex\" width=\"1024\" height=\"569\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-01-1024x569.png 1024w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-01-980x544.png 980w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-01-480x267.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-02.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3815\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-02.png\" alt=\"New Shimano 600 Ex\" width=\"830\" height=\"618\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-02.png 830w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-02-480x357.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 830px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-03.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3816\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-03.png\" alt=\"New Shimano 600 Ex\" width=\"862\" height=\"617\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-03.png 862w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-03-480x344.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 862px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-04.png\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-full wp-image-3817\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-04.png\" alt=\"New Shimano 600 Ex\" width=\"860\" height=\"611\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-04.png 860w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Shimano-600ex-new-04-480x341.png 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 860px, 100vw\" \/><\/a><\/p>\n<h3><strong>Components<\/strong><\/h3>\n<ul>\n<li><strong>frame:<\/strong> ??<\/li>\n<li><strong>Brake levers <\/strong>New Shimano 600 Ex<\/li>\n<li><strong>Brake calipers<\/strong> New Shimano 600 Ex<\/li>\n<li><strong>Gear levers, front and rear derailleur:<\/strong> New Shimano 600 Ex<\/li>\n<li><strong>Crankset:\u00a0<\/strong>New Shimano 600 Ex<\/li>\n<li><strong>sprocket wheels: <\/strong>New Shimano 600 Ex<\/li>\n<li><strong>Hubs <\/strong>New Shimano 600 Ex<\/li>\n<li><strong>Rims:<\/strong> Mavic GP4<\/li>\n<li><strong>Headset:<\/strong>\u00a0New Shimano 600 Ex<\/li>\n<li><strong>Stem:<\/strong> Cinelli<\/li>\n<li><strong>Handlebar:<\/strong> 3ttt modello Competizione<\/li>\n<li><strong>Saddle: <\/strong>San Marco<\/li>\n<li><strong>Seatpost: <\/strong>Sakae Ringo<\/li>\n<li><strong>Frontderailleur:<\/strong>\u00a0New Shimano 600 Ex<\/li>\n<li><strong>Rear derailleur:<\/strong>\u00a0New Shimano 600 Ex<\/li>\n<li><strong>bottom bracket:<\/strong>\u00a0New Shimano 600 Ex<\/li>\n<li><strong>Pedals<\/strong> New Shimano 600 Ex<\/li>\n<\/ul>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin26-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3821\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin26-1024x496.jpg\" alt=\"Rossin racefiets\" width=\"1024\" height=\"496\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin26-1024x496.jpg 1024w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin26-980x474.jpg 980w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin26-480x232.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin24-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3822\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin24-1024x496.jpg\" alt=\"Rossin racefiets\" width=\"1024\" height=\"496\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin24-1024x496.jpg 1024w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin24-980x474.jpg 980w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin24-480x232.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin25-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3823 aligncenter\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin25-496x1024.jpg\" alt=\"Rossin racefiets\" width=\"496\" height=\"1024\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin25-496x1024.jpg 496w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin25-480x992.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 496px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin10-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3824\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin10-1024x496.jpg\" alt=\"Rossin racefiets\" width=\"1024\" height=\"496\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin10-1024x496.jpg 1024w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin10-980x474.jpg 980w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin10-480x232.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin09-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3825\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin09-1024x496.jpg\" alt=\"Rossin racefiets\" width=\"1024\" height=\"496\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin09-1024x496.jpg 1024w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin09-980x474.jpg 980w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin09-480x232.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin08-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3826 aligncenter\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin08-496x1024.jpg\" alt=\"Rossin racefiets\" width=\"496\" height=\"1024\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin08-496x1024.jpg 496w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin08-480x992.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 496px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin07-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3827\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin07-1024x496.jpg\" alt=\"Rossin racefiets\" width=\"1024\" height=\"496\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin07-1024x496.jpg 1024w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin07-980x474.jpg 980w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin07-480x232.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin13-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3828 aligncenter\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin13-496x1024.jpg\" alt=\"Rossin racefiets\" width=\"496\" height=\"1024\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin13-496x1024.jpg 496w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin13-480x992.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 496px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin15-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3829 aligncenter\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin15-496x1024.jpg\" alt=\"Rossin racefiets\" width=\"496\" height=\"1024\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin15-496x1024.jpg 496w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin15-480x992.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 496px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin17-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3830\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin17-1024x496.jpg\" alt=\"Rossin racefiets\" width=\"1024\" height=\"496\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin17-1024x496.jpg 1024w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin17-980x474.jpg 980w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin17-480x232.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin22-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3831\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin22-1024x496.jpg\" alt=\"Shimano 600 Ex\" width=\"1024\" height=\"496\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin22-1024x496.jpg 1024w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin22-980x474.jpg 980w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin22-480x232.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin21-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3832 aligncenter\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin21-496x1024.jpg\" alt=\"New Shimano 600 Ex\" width=\"496\" height=\"1024\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin21-496x1024.jpg 496w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin21-480x992.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 496px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin19-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3833\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin19-1024x496.jpg\" alt=\"Vintage 3tt stuur\" width=\"1024\" height=\"496\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin19-1024x496.jpg 1024w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin19-980x474.jpg 980w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin19-480x232.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin18-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-3834 aligncenter\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin18-496x1024.jpg\" alt=\"Cinelli stuurpen\" width=\"496\" height=\"1024\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin18-496x1024.jpg 496w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin18-480x992.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) 496px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin12-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3835\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin12-1024x496.jpg\" alt=\"San Marco zadel\" width=\"1024\" height=\"496\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin12-1024x496.jpg 1024w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin12-980x474.jpg 980w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin12-480x232.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin02-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3836\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin02-1024x496.jpg\" alt=\"Rossin racefiets\" width=\"1024\" height=\"496\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin02-1024x496.jpg 1024w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin02-980x474.jpg 980w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin02-480x232.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin04-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone size-large wp-image-3837\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin04-1024x496.jpg\" alt=\"New Shimano 600 Ex\" width=\"1024\" height=\"496\" srcset=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin04-1024x496.jpg 1024w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin04-980x474.jpg 980w, https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin04-480x232.jpg 480w\" sizes=\"auto, (min-width: 0px) and (max-width: 480px) 480px, (min-width: 481px) and (max-width: 980px) 980px, (min-width: 981px) 1024px, 100vw\" \/><\/a><\/p>\n<p><a href=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin06-scaled.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"alignnone wp-image-3838 size-large\" src=\"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin06-1024x496.jpg\" alt=\"Mavic velgen\" width=\"1024\" height=\"496\" \/><\/a><\/p>\n<p>&nbsp;<\/p>","protected":false},"excerpt":{"rendered":"<p>The bike in the spotlight this time is a Replica of an Italian Rossin from the early 80s equipped with a complete group of New Shimano 600 Ex<\/p>","protected":false},"author":1,"featured_media":3818,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[214],"tags":[36,216,870,869,155,613,612],"class_list":["post-3812","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-vintagefietsen-verzamelaars","tag-italiaanse-fietsen","tag-italiaanse-fietsmerken","tag-new-shimano-600-ex","tag-rossin","tag-shimano","tag-verzamelaars-retro-fietsen","tag-verzamelaars-vintage-fietsen"],"aioseo_notices":[],"aioseo_head":"\n\t\t<!-- All in One SEO 5.0.0.1 - aioseo.com -->\n\t<meta name=\"description\" content=\"De fiets in de kijker is deze keer een Replica van een Italiaanse Rossin uit begin jaren 80 uitgerust met een complete groep New Shimano 600 Ex zoals\" \/>\n\t<meta name=\"robots\" content=\"max-image-preview:large\" \/>\n\t<meta name=\"author\" content=\"Gunther Desaever\"\/>\n\t<meta name=\"keywords\" content=\"italiaanse fietsen,italiaanse fietsmerken,new shimano 600 ex,rossin,shimano,verzamelaars retro fietsen,verzamelaars vintage fietsen\" \/>\n\t<link rel=\"canonical\" href=\"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/\" \/>\n\t<meta name=\"generator\" content=\"All in One SEO (AIOSEO) 5.0.0.1\" \/>\n\t\t<meta property=\"og:locale\" content=\"en_GB\" \/>\n\t\t<meta property=\"og:site_name\" content=\"Vintagefiets | De site voor liefhebbers van vintage fietsen\" \/>\n\t\t<meta property=\"og:type\" content=\"article\" \/>\n\t\t<meta property=\"og:title\" content=\"Fiets in de kijker: Rossin replica jaren \u201980 | Vintagefiets\" \/>\n\t\t<meta property=\"og:description\" content=\"De fiets in de kijker is deze keer een Replica van een Italiaanse Rossin uit begin jaren 80 uitgerust met een complete groep New Shimano 600 Ex zoals\" \/>\n\t\t<meta property=\"og:url\" content=\"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/\" \/>\n\t\t<meta property=\"article:published_time\" content=\"2022-03-17T15:57:58+00:00\" \/>\n\t\t<meta property=\"article:modified_time\" content=\"2022-03-17T16:00:38+00:00\" \/>\n\t\t<meta name=\"twitter:card\" content=\"summary\" \/>\n\t\t<meta name=\"twitter:title\" content=\"Fiets in de kijker: Rossin replica jaren \u201980 | Vintagefiets\" \/>\n\t\t<meta name=\"twitter:description\" content=\"De fiets in de kijker is deze keer een Replica van een Italiaanse Rossin uit begin jaren 80 uitgerust met een complete groep New Shimano 600 Ex zoals\" \/>\n\t\t<script type=\"application\/ld+json\" class=\"aioseo-schema\">\n\t\t\t{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/fiets-in-de-kijker-rossin-replica-jaren-80\\\/#article\",\"name\":\"Fiets in de kijker: Rossin replica jaren \\u201980 | Vintagefiets\",\"headline\":\"Fiets in de kijker: Rossin replica jaren &#8217;80\",\"author\":{\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/author\\\/admin\\\/#author\"},\"publisher\":{\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/#person\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.vintagefiets.be\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Rossin03-scaled.jpg\",\"width\":1000,\"height\":484,\"caption\":\"Rossin racefiets\"},\"datePublished\":\"2022-03-17T15:57:58+00:00\",\"dateModified\":\"2022-03-17T16:00:38+00:00\",\"inLanguage\":\"en-GB\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/fiets-in-de-kijker-rossin-replica-jaren-80\\\/#webpage\"},\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/fiets-in-de-kijker-rossin-replica-jaren-80\\\/#webpage\"},\"articleSection\":\"Vintagefietsen verzamelaars, Italiaanse fietsen, Italiaanse fietsmerken, New Shimano 600 Ex, Rossin, Shimano, Verzamelaars retro fietsen, Verzamelaars vintage fietsen\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/fiets-in-de-kijker-rossin-replica-jaren-80\\\/#breadcrumblist\",\"itemListElement\":[{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en#listItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/category\\\/vintagefietsen-verzamelaars\\\/#listItem\",\"name\":\"Vintagefietsen verzamelaars\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/category\\\/vintagefietsen-verzamelaars\\\/#listItem\",\"position\":2,\"name\":\"Vintagefietsen verzamelaars\",\"item\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/category\\\/vintagefietsen-verzamelaars\\\/\",\"nextItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/fiets-in-de-kijker-rossin-replica-jaren-80\\\/#listItem\",\"name\":\"Fiets in de kijker: Rossin replica jaren &#8217;80\"},\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en#listItem\",\"name\":\"Home\"}},{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/fiets-in-de-kijker-rossin-replica-jaren-80\\\/#listItem\",\"position\":3,\"name\":\"Fiets in de kijker: Rossin replica jaren &#8217;80\",\"previousItem\":{\"@type\":\"ListItem\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/category\\\/vintagefietsen-verzamelaars\\\/#listItem\",\"name\":\"Vintagefietsen verzamelaars\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/#person\",\"name\":\"Gunther Desaever\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/fiets-in-de-kijker-rossin-replica-jaren-80\\\/#personImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/016d4d7711396cda7d733fc35083fd27965ed29cf1c41d5f398638f188963420?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Gunther Desaever\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/author\\\/admin\\\/#author\",\"url\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/author\\\/admin\\\/\",\"name\":\"Gunther Desaever\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/fiets-in-de-kijker-rossin-replica-jaren-80\\\/#authorImage\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/016d4d7711396cda7d733fc35083fd27965ed29cf1c41d5f398638f188963420?s=96&d=mm&r=g\",\"width\":96,\"height\":96,\"caption\":\"Gunther Desaever\"}},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/fiets-in-de-kijker-rossin-replica-jaren-80\\\/#webpage\",\"url\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/fiets-in-de-kijker-rossin-replica-jaren-80\\\/\",\"name\":\"Fiets in de kijker: Rossin replica jaren \\u201980 | Vintagefiets\",\"description\":\"De fiets in de kijker is deze keer een Replica van een Italiaanse Rossin uit begin jaren 80 uitgerust met een complete groep New Shimano 600 Ex zoals\",\"inLanguage\":\"en-GB\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/fiets-in-de-kijker-rossin-replica-jaren-80\\\/#breadcrumblist\"},\"author\":{\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/author\\\/admin\\\/#author\"},\"creator\":{\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/author\\\/admin\\\/#author\"},\"image\":{\"@type\":\"ImageObject\",\"url\":\"https:\\\/\\\/www.vintagefiets.be\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/Rossin03-scaled.jpg\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/fiets-in-de-kijker-rossin-replica-jaren-80\\\/#mainImage\",\"width\":1000,\"height\":484,\"caption\":\"Rossin racefiets\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/fiets-in-de-kijker-rossin-replica-jaren-80\\\/#mainImage\"},\"datePublished\":\"2022-03-17T15:57:58+00:00\",\"dateModified\":\"2022-03-17T16:00:38+00:00\"},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/\",\"name\":\"Vintagefiets\",\"description\":\"De site voor liefhebbers van vintage fietsen\",\"inLanguage\":\"en-GB\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.vintagefiets.be\\\/en\\\/#person\"}}]}\n\t\t<\/script>\n\t\t<!-- All in One SEO -->\n\n","aioseo_head_json":{"title":"Fiets in de kijker: Rossin replica jaren \u201980 | Vintagefiets","description":"The bike in the spotlight this time is a Replica of an Italian Rossin from the early 80s equipped with a complete group of New Shimano 600 Ex","canonical_url":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/","robots":"max-image-preview:large","keywords":"italiaanse fietsen,italiaanse fietsmerken,new shimano 600 ex,rossin,shimano,verzamelaars retro fietsen,verzamelaars vintage fietsen","webmasterTools":{"miscellaneous":""},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/#article","name":"Fiets in de kijker: Rossin replica jaren \u201980 | Vintagefiets","headline":"Fiets in de kijker: Rossin replica jaren &#8217;80","author":{"@id":"https:\/\/www.vintagefiets.be\/en\/author\/admin\/#author"},"publisher":{"@id":"https:\/\/www.vintagefiets.be\/en\/#person"},"image":{"@type":"ImageObject","url":"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin03-scaled.jpg","width":1000,"height":484,"caption":"Rossin racefiets"},"datePublished":"2022-03-17T15:57:58+00:00","dateModified":"2022-03-17T16:00:38+00:00","inLanguage":"en-GB","mainEntityOfPage":{"@id":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/#webpage"},"isPartOf":{"@id":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/#webpage"},"articleSection":"Vintagefietsen verzamelaars, Italiaanse fietsen, Italiaanse fietsmerken, New Shimano 600 Ex, Rossin, Shimano, Verzamelaars retro fietsen, Verzamelaars vintage fietsen"},{"@type":"BreadcrumbList","@id":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/#breadcrumblist","itemListElement":[{"@type":"ListItem","@id":"https:\/\/www.vintagefiets.be\/en#listItem","position":1,"name":"Home","item":"https:\/\/www.vintagefiets.be\/en","nextItem":{"@type":"ListItem","@id":"https:\/\/www.vintagefiets.be\/en\/category\/vintagefietsen-verzamelaars\/#listItem","name":"Vintagefietsen verzamelaars"}},{"@type":"ListItem","@id":"https:\/\/www.vintagefiets.be\/en\/category\/vintagefietsen-verzamelaars\/#listItem","position":2,"name":"Vintagefietsen verzamelaars","item":"https:\/\/www.vintagefiets.be\/en\/category\/vintagefietsen-verzamelaars\/","nextItem":{"@type":"ListItem","@id":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/#listItem","name":"Fiets in de kijker: Rossin replica jaren &#8217;80"},"previousItem":{"@type":"ListItem","@id":"https:\/\/www.vintagefiets.be\/en#listItem","name":"Home"}},{"@type":"ListItem","@id":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/#listItem","position":3,"name":"Fiets in de kijker: Rossin replica jaren &#8217;80","previousItem":{"@type":"ListItem","@id":"https:\/\/www.vintagefiets.be\/en\/category\/vintagefietsen-verzamelaars\/#listItem","name":"Vintagefietsen verzamelaars"}}]},{"@type":"Person","@id":"https:\/\/www.vintagefiets.be\/en\/#person","name":"Gunther Desaever","image":{"@type":"ImageObject","@id":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/#personImage","url":"https:\/\/secure.gravatar.com\/avatar\/016d4d7711396cda7d733fc35083fd27965ed29cf1c41d5f398638f188963420?s=96&d=mm&r=g","width":96,"height":96,"caption":"Gunther Desaever"}},{"@type":"Person","@id":"https:\/\/www.vintagefiets.be\/en\/author\/admin\/#author","url":"https:\/\/www.vintagefiets.be\/en\/author\/admin\/","name":"Gunther Desaever","image":{"@type":"ImageObject","@id":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/#authorImage","url":"https:\/\/secure.gravatar.com\/avatar\/016d4d7711396cda7d733fc35083fd27965ed29cf1c41d5f398638f188963420?s=96&d=mm&r=g","width":96,"height":96,"caption":"Gunther Desaever"}},{"@type":"WebPage","@id":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/#webpage","url":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/","name":"Fiets in de kijker: Rossin replica jaren \u201980 | Vintagefiets","description":"De fiets in de kijker is deze keer een Replica van een Italiaanse Rossin uit begin jaren 80 uitgerust met een complete groep New Shimano 600 Ex zoals","inLanguage":"en-GB","isPartOf":{"@id":"https:\/\/www.vintagefiets.be\/en\/#website"},"breadcrumb":{"@id":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/#breadcrumblist"},"author":{"@id":"https:\/\/www.vintagefiets.be\/en\/author\/admin\/#author"},"creator":{"@id":"https:\/\/www.vintagefiets.be\/en\/author\/admin\/#author"},"image":{"@type":"ImageObject","url":"https:\/\/www.vintagefiets.be\/wp-content\/uploads\/2022\/03\/Rossin03-scaled.jpg","@id":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/#mainImage","width":1000,"height":484,"caption":"Rossin racefiets"},"primaryImageOfPage":{"@id":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/#mainImage"},"datePublished":"2022-03-17T15:57:58+00:00","dateModified":"2022-03-17T16:00:38+00:00"},{"@type":"WebSite","@id":"https:\/\/www.vintagefiets.be\/en\/#website","url":"https:\/\/www.vintagefiets.be\/en\/","name":"Vintagefiets","description":"De site voor liefhebbers van vintage fietsen","inLanguage":"en-GB","publisher":{"@id":"https:\/\/www.vintagefiets.be\/en\/#person"}}]},"og:locale":"en_GB","og:site_name":"Vintagefiets | De site voor liefhebbers van vintage fietsen","og:type":"article","og:title":"Fiets in de kijker: Rossin replica jaren \u201980 | Vintagefiets","og:description":"De fiets in de kijker is deze keer een Replica van een Italiaanse Rossin uit begin jaren 80 uitgerust met een complete groep New Shimano 600 Ex zoals","og:url":"https:\/\/www.vintagefiets.be\/en\/fiets-in-de-kijker-rossin-replica-jaren-80\/","article:published_time":"2022-03-17T15:57:58+00:00","article:modified_time":"2022-03-17T16:00:38+00:00","twitter:card":"summary","twitter:title":"Fiets in de kijker: Rossin replica jaren \u201980 | Vintagefiets","twitter:description":"De fiets in de kijker is deze keer een Replica van een Italiaanse Rossin uit begin jaren 80 uitgerust met een complete groep New Shimano 600 Ex zoals"},"aioseo_meta_data":{"post_id":"3812","title":null,"description":"#post_excerpt","keywords":[],"keyphrases":{"focus":{"keyphrase":"","score":0,"analysis":{"keyphraseInTitle":{"score":0,"maxScore":9,"error":1}}},"additional":[]},"primary_term":null,"canonical_url":null,"og_title":null,"og_description":null,"og_object_type":"default","og_image_type":"default","og_image_url":null,"og_image_width":null,"og_image_height":null,"og_image_custom_url":null,"og_image_custom_fields":null,"og_video":"","og_custom_url":null,"og_article_section":null,"og_article_tags":[],"twitter_use_og":false,"twitter_card":"default","twitter_image_type":"default","twitter_image_url":null,"twitter_image_custom_url":null,"twitter_image_custom_fields":null,"twitter_title":null,"twitter_description":null,"schema":{"blockGraphs":[],"customGraphs":[],"default":{"data":{"Article":[],"Course":[],"Dataset":[],"FAQPage":[],"Movie":[],"Person":[],"Product":[],"ProductReview":[],"Car":[],"Recipe":[],"Service":[],"SoftwareApplication":[],"WebPage":[]},"graphName":"","isEnabled":true},"graphs":[],"defaultGraph":"Article","defaultPostTypeGraph":""},"schema_type":"default","schema_type_options":"{\"article\":{\"articleType\":\"BlogPosting\"},\"course\":{\"name\":\"\",\"description\":\"\",\"provider\":\"\"},\"faq\":{\"pages\":[]},\"product\":{\"reviews\":[]},\"recipe\":{\"ingredients\":[],\"instructions\":[],\"keywords\":[]},\"software\":{\"reviews\":[],\"operatingSystems\":[]},\"webPage\":{\"webPageType\":\"WebPage\"}}","pillar_content":false,"robots_default":true,"robots_noindex":false,"robots_noarchive":false,"robots_nosnippet":false,"robots_nofollow":false,"robots_noimageindex":false,"robots_noodp":false,"robots_notranslate":false,"robots_max_snippet":"-1","robots_max_videopreview":"-1","robots_max_imagepreview":"large","priority":null,"frequency":"default","local_seo":null,"breadcrumb_settings":null,"limit_modified_date":false,"ai":null,"created":"2022-03-17 08:38:06","updated":"2025-12-16 15:39:08","seo_analyzer_scan_date":null,"focus_keyword":null,"additional_keywords":null,"truseo_locale":null},"_links":{"self":[{"href":"https:\/\/www.vintagefiets.be\/en\/wp-json\/wp\/v2\/posts\/3812","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.vintagefiets.be\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.vintagefiets.be\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.vintagefiets.be\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.vintagefiets.be\/en\/wp-json\/wp\/v2\/comments?post=3812"}],"version-history":[{"count":4,"href":"https:\/\/www.vintagefiets.be\/en\/wp-json\/wp\/v2\/posts\/3812\/revisions"}],"predecessor-version":[{"id":3842,"href":"https:\/\/www.vintagefiets.be\/en\/wp-json\/wp\/v2\/posts\/3812\/revisions\/3842"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.vintagefiets.be\/en\/wp-json\/wp\/v2\/media\/3818"}],"wp:attachment":[{"href":"https:\/\/www.vintagefiets.be\/en\/wp-json\/wp\/v2\/media?parent=3812"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.vintagefiets.be\/en\/wp-json\/wp\/v2\/categories?post=3812"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.vintagefiets.be\/en\/wp-json\/wp\/v2\/tags?post=3812"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}